{"id":13691,"date":"2026-06-23T16:32:46","date_gmt":"2026-06-23T14:32:46","guid":{"rendered":"https:\/\/haut-de-rosans.geek-tonic.dev\/datenschutzrichtlinie\/"},"modified":"2026-07-13T13:32:12","modified_gmt":"2026-07-13T11:32:12","slug":"datenschutzrichtlinie","status":"publish","type":"page","link":"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/datenschutzrichtlinie\/","title":{"rendered":"Datenschutzrichtlinie"},"content":{"rendered":"\n<section class=\"wp-block-group banner-imgs not-slider is-nowrap is-layout-flex wp-container-core-group-is-layout-3a88641f wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1745\" height=\"582\" src=\"https:\/\/haut-de-rosans.geek-tonic.dev\/wp-content\/uploads\/2026\/07\/politique-de-confidentialite-camping-les-hauts-de-rosans.jpg\" alt=\"Datenschutzrichtlinie des Campingplatzes &#x201E;les hauts de rosans&#x201C;\" class=\"wp-image-4897\" style=\"border-top-left-radius:36px;border-top-right-radius:36px;border-bottom-left-radius:36px;border-bottom-right-radius:36px;object-fit:cover\"\/><\/figure>\n<\/section>\n\n<section class=\"wp-block-group section-1 has-global-padding is-layout-constrained wp-container-core-group-is-layout-facc8737 wp-block-group-is-layout-constrained\" style=\"padding-top:4rem;padding-right:0px;padding-bottom:4rem;padding-left:0px\">\n<div class=\"wp-block-group top-content has-global-padding is-layout-constrained wp-container-core-group-is-layout-8a16f700 wp-block-group-is-layout-constrained\" style=\"padding-right:10rem;padding-left:10rem\">\n<h1 class=\"wp-block-heading has-text-align-center\"><strong>Datenschutzrichtlinie<\/strong><\/h1>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Diese Datenschutzrichtlinie beschreibt, welche personenbezogenen Daten bei der Nutzung der Website erhoben oder generiert (verarbeitet) werden. Diese Datenschutzrichtlinie beschreibt, welche Arten von personenbezogenen Daten bei der Nutzung unserer Website erhoben werden und wie Ihre personenbezogenen Daten verwendet, weitergegeben und gesch\u00fctzt werden. Au\u00dferdem erl\u00e4utert sie, welche Wahlm\u00f6glichkeiten Sie hinsichtlich Ihrer personenbezogenen Daten haben und wie Sie uns kontaktieren k\u00f6nnen.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"margin-top:var(--wp--preset--spacing--30)\">Inhaltsverzeichnis<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#gdpr-1\">Wer sind wir?<\/a><\/li>\n\n\n\n<li><a href=\"#gdpr-2\">Verwendung der erhobenen personenbezogenen Daten<\/a><\/li>\n\n\n\n<li><a href=\"#gdpr-3\">Kommentare<\/a><\/li>\n\n\n\n<li><a href=\"#gdpr-4\">Medien<\/a><\/li>\n\n\n\n<li><a href=\"#gdpr-5\">Kontaktformulare<\/a><\/li>\n\n\n\n<li><a href=\"#gdpr-6\">Verwendung von Cookies<\/a><\/li>\n\n\n\n<li><a href=\"#gdpr-7\">Statistiken und Reichweitenmessungen<\/a><\/li>\n\n\n\n<li><a href=\"#gdpr-8\">Aufbewahrungsfristen f\u00fcr Ihre Daten<\/a><\/li>\n\n\n\n<li><a href=\"#gdpr-9\">Ihre Rechte in Bezug auf Ihre Daten<\/a><\/li>\n\n\n\n<li><a href=\"#gdpr-10\">Weitergabe Ihrer personenbezogenen Daten<\/a><\/li>\n\n\n\n<li><a href=\"#gdpr-11\">Wie wir Ihre Daten sch\u00fctzen<\/a><\/li>\n\n\n\n<li><a href=\"#gdpr-12\">Kontaktdaten<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-1\" style=\"margin-top:var(--wp--preset--spacing--30)\">Wer sind wir?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Alle Informationen hierzu finden Sie auf der Seite <a href=\"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/impressum\/\">Impressum<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-2\" style=\"margin-top:var(--wp--preset--spacing--30)\">Verwendung der erhobenen personenbezogenen Daten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir erheben automatisch und direkt keinerlei Daten \u00fcber Sie. Ungeachtet dessen k\u00f6nnen wir Informationen, einschlie\u00dflich personenbezogener Daten, von Dritten erheben (siehe Abschnitt <a href=\"#gdpr-5\">\u201eCookies\u201c<\/a>). <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-3\" style=\"margin-top:var(--wp--preset--spacing--30)\">Kommentare<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie einen Kommentar auf unserer Website hinterlassen, werden die im Kommentarformular eingegebenen Daten sowie Ihre IP-Adresse und der User-Agent Ihres Browsers erfasst, um uns bei der Erkennung unerw\u00fcnschter Kommentare zu unterst\u00fctzen. Eine aus Ihrer E-Mail-Adresse erstellte anonymisierte Zeichenfolge (auch als Hash bezeichnet) kann an den Gravatar-Dienst \u00fcbermittelt werden, um zu \u00fcberpr\u00fcfen, ob Sie diesen nutzen. Die Datenschutzbestimmungen des Gravatar-Dienstes finden Sie unter https:\/\/automattic.com\/privacy\/. Nach der Freigabe Ihres Kommentars wird Ihr Profilbild \u00f6ffentlich neben Ihrem Kommentar angezeigt.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-4\" style=\"margin-top:var(--wp--preset--spacing--30)\">Medien<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie ein registrierter Nutzer oder eine registrierte Nutzerin sind und Bilder auf die Website hochladen, empfehlen wir Ihnen, keine Bilder hochzuladen, die EXIF-Daten mit GPS-Koordinaten enthalten. Besucher Ihrer Website k\u00f6nnen diese Bilder herunterladen und die Standortdaten daraus extrahieren. <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-5\" style=\"margin-top:var(--wp--preset--spacing--30)\">Kontaktformulare<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sie k\u00f6nnen uns Informationen \u00fcbermitteln, wenn Sie ein Formular ausf\u00fcllen; diese werden uns per E-Mail \u00fcbermittelt und ausschlie\u00dflich in unserem E-Mail-System gespeichert; diese Informationen werden ausschlie\u00dflich zum Zweck der Beantwortung Ihrer Anfrage verwendet. Sollten Informationen f\u00fcr kommerzielle Zwecke verwendet werden k\u00f6nnen, wird dies am Ende des Formulars entsprechend vermerkt. Wir werden stets Ihre Einwilligung einholen, wenn wir Informationen \u00fcber ein Formular erfassen.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-6\" style=\"margin-top:var(--wp--preset--spacing--30)\">Verwendung von Cookies<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Was ist ein Cookie?<\/strong> <br\/>Ein Cookie ist eine kleine Datendatei, die auf Ihr Ger\u00e4t \u00fcbertragen und dort gespeichert wird. Konkret erm\u00f6glicht uns ein Cookie beispielsweise, Ihren Browser oder Ihre Sprache zu erkennen oder Ihre Einstellungen zu speichern.  <br\/>Auf unserer Website werden zwei Arten von Cookies verwendet: \u201eSitzungs-Cookies\u201c und \u201edauerhafte Cookies\u201c. Sitzungs-Cookies verfallen, sobald Sie Ihren Browser schlie\u00dfen, w\u00e4hrend dauerhafte Cookies auch nach dem Schlie\u00dfen Ihres Browsers auf Ihrem Ger\u00e4t verbleiben und bei Ihrem n\u00e4chsten Besuch auf unserer Website erneut verwendet werden k\u00f6nnen. <br\/>Weitere Informationen finden Sie unter <a href=\"https:\/\/allaboutcookies.org\/fr\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">allaboutcookies.org<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Unsere Cookies<\/strong> <br\/>Wenn Sie einen Kommentar auf unserer Website hinterlassen, wird Ihnen angeboten, Ihren Namen, Ihre E-Mail-Adresse und Ihre Website in Cookies zu speichern. Dies dient ausschlie\u00dflich Ihrem Komfort, damit Sie diese Angaben nicht erneut eingeben m\u00fcssen, falls Sie sp\u00e4ter einen weiteren Kommentar hinterlassen. Diese Cookies verfallen nach einem Jahr. Wenn Sie ein Konto besitzen und sich auf dieser Website anmelden, wird ein tempor\u00e4res Cookie erstellt, um festzustellen, ob Ihr Browser Cookies akzeptiert. Es enth\u00e4lt keine personenbezogenen Daten und wird automatisch gel\u00f6scht, sobald Sie Ihren Browser schlie\u00dfen. Wenn Sie sich anmelden, setzen wir eine Reihe von Cookies, um Ihre Anmeldedaten und Ihre Bildschirmeinstellungen zu speichern. Die Lebensdauer eines Anmelde-Cookies betr\u00e4gt zwei Tage, die eines Cookies f\u00fcr die Bildschirmeinstellungen ein Jahr. Wenn Sie \u201eAngemeldet bleiben\u201c aktivieren, wird Ihr Anmelde-Cookie zwei Wochen lang gespeichert. Wenn Sie sich von Ihrem Konto abmelden, wird das Anmelde-Cookie gel\u00f6scht. Beim Bearbeiten oder Ver\u00f6ffentlichen eines Beitrags wird ein zus\u00e4tzliches Cookie in Ihrem Browser gespeichert. Dieses Cookie enth\u00e4lt keine personenbezogenen Daten. Es gibt lediglich die Kennung des Beitrags an, den Sie gerade bearbeitet haben. Es l\u00e4uft nach einem Tag ab.            <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cookies von Drittanbietern<\/strong> <br\/>Die Beitr\u00e4ge auf dieser Website k\u00f6nnen eingebettete Inhalte enthalten (z. B. Videos, Bilder, Artikel\u2026). Die von anderen Websites eingebetteten Inhalte verhalten sich genauso, als w\u00fcrde der Besucher diese andere Website direkt aufrufen. Diese Websites k\u00f6nnten Daten \u00fcber Sie erfassen, Cookies verwenden, Tracking-Tools von Drittanbietern einbinden und Ihre Interaktionen mit diesen eingebetteten Inhalten nachverfolgen, sofern Sie auf deren Website \u00fcber ein angemeldetes Konto verf\u00fcgen. Wir behalten uns vor, bestimmten Gesch\u00e4ftspartnern zu gestatten, Technologien auf unserer Website zu installieren. Diese Partner nutzen diese Technologien, um uns dabei zu unterst\u00fctzen, Ihre Nutzung der Website zu analysieren \u2013 beispielsweise indem sie erfassen, \u00fcber welche Dienste Dritter Sie auf die Plattform gelangt sind \u2013, unsere Dienste auf unserer Website und auf Websites Dritter zu vermarkten und zu bewerben, uns dabei zu unterst\u00fctzen, Betrugsf\u00e4lle aufzudecken und zu verhindern oder Risikobewertungen durchzuf\u00fchren, oder Informationen \u00fcber Ihre Aktivit\u00e4ten auf der Website zu erfassen.     Unsere Website kann Social-Media-Plugins verwenden, die von Drittanbietern bereitgestellt und betrieben werden, wie beispielsweise die \u201eGef\u00e4llt mir\u201c-Schaltfl\u00e4che von Facebook. Infolgedessen k\u00f6nnen Sie die Informationen, die Sie in einem bestimmten Bereich unserer Website aufrufen, an den Drittanbieter \u00fcbermitteln. Wenn Sie nicht in Ihrem Konto bei dem Drittanbieter angemeldet sind, kann dieser Ihre Identit\u00e4t nicht ermitteln. Sind Sie hingegen in Ihrem Konto bei dem Drittanbieter angemeldet, kann dieser die Informationen oder Aktionen im Zusammenhang mit Ihren Interaktionen auf unserer Website mit dem Konto verkn\u00fcpfen, das Sie bei dem betreffenden Drittanbieter unterhalten. Bitte lesen Sie die Datenschutzrichtlinien des Drittanbieters, um mehr \u00fcber dessen Datenpraktiken zu erfahren.     Die Liste der auf dieser Website verwendeten Cookies von Drittanbietern k\u00f6nnen Sie \u00fcber das <a href=\"#moove_gdpr_cookie_modal\">Cookie-Verwaltungsfenster<\/a> einsehen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-7\" style=\"margin-top:var(--wp--preset--spacing--30)\">Statistiken und Reichweitenmessungen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Bereich der Analyse arbeiten wir mit Google Analytics, um Informationen \u00fcber die Nutzung unserer Website zu erhalten und diese zu verbessern. Diese Funktion kann \u00fcber das <a href=\"#moove_gdpr_cookie_modal\">Cookie-Einstellungsmen\u00fc<\/a> deaktiviert werden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um zu verhindern, dass Google Analytics Ihre Daten zu Analysezwecken verwendet, k\u00f6nnen Sie auch das Browser-Add-on zur Deaktivierung von Google Analytics installieren, indem Sie <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a> klicken. Bitte beachten Sie, dass wir keinen Einfluss auf diesen Deaktivierungslink haben und nicht f\u00fcr die Verf\u00fcgbarkeit oder Richtigkeit dieses Mechanismus verantwortlich sind. Weitere Informationen finden Sie in <a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245\" target=\"_blank\" rel=\"noreferrer noopener\">dieser Dokumentation<\/a>.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-8\" style=\"margin-top:var(--wp--preset--spacing--30)\">Aufbewahrungsfristen f\u00fcr Ihre Daten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie einen Kommentar hinterlassen, werden dieser und seine Metadaten auf unbestimmte Zeit gespeichert. Dadurch k\u00f6nnen nachfolgende Kommentare automatisch erkannt und freigegeben werden, anstatt sie in der Moderationswarteschlange zu belassen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr Nutzer und Nutzerinnen, die sich auf unserer Website registrieren (sofern dies m\u00f6glich ist), speichern wir zudem die in ihrem Profil angegebenen personenbezogenen Daten. Alle Nutzer und Nutzerinnen k\u00f6nnen ihre personenbezogenen Daten jederzeit einsehen, \u00e4ndern oder l\u00f6schen (mit Ausnahme ihres Benutzernamens).  Die Administratoren der Website k\u00f6nnen diese Informationen ebenfalls einsehen und bearbeiten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-9\" style=\"margin-top:var(--wp--preset--spacing--30)\">Ihre Rechte in Bezug auf Ihre Daten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie ein Konto haben oder Kommentare auf der Website hinterlassen haben, k\u00f6nnen Sie eine Datei anfordern, die alle personenbezogenen Daten enth\u00e4lt, die wir \u00fcber Sie gespeichert haben, einschlie\u00dflich derer, die Sie uns zur Verf\u00fcgung gestellt haben. Sie k\u00f6nnen au\u00dferdem die L\u00f6schung Ihrer personenbezogenen Daten beantragen. Davon ausgenommen sind Daten, die zu administrativen, rechtlichen oder Sicherheitszwecken gespeichert werden.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-10\" style=\"margin-top:var(--wp--preset--spacing--30)\">Weitergabe Ihrer personenbezogenen Daten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Kommentare der Besucher k\u00f6nnen mithilfe eines automatisierten Dienstes zur Erkennung unerw\u00fcnschter Kommentare \u00fcberpr\u00fcft werden. Alle personenbezogenen Daten, die wir verarbeiten, werden innerhalb der Europ\u00e4ischen Union verarbeitet. <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-11\" style=\"margin-top:var(--wp--preset--spacing--30)\">Wie wir Ihre Daten sch\u00fctzen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir richten <strong>Sicherheitsma\u00dfnahmen<\/strong> f\u00fcr die Website ein und aktualisieren diese kontinuierlich, um Ihre Daten vor unbefugtem Zugriff, Verlust, Zerst\u00f6rung oder Manipulation zu sch\u00fctzen. Wir sind daher bestrebt, Ihre Daten so sicher wie m\u00f6glich zu machen. Da das Internet keine zu 100 % sichere Umgebung ist, k\u00f6nnen wir die Sicherheit bei der \u00dcbertragung oder Speicherung Ihrer Daten nicht vollst\u00e4ndig garantieren.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"gdpr-12\" style=\"margin-top:var(--wp--preset--spacing--30)\">Kontaktdaten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei Anfragen oder Fragen zu Ihren personenbezogenen Daten wenden Sie sich bitte an rgpd@geek-tonic.com; weitere Kontaktdaten finden Sie in unserem <a href=\"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/impressum\/\">Impressum<\/a>. Bitte beachten Sie, dass wir Sie m\u00f6glicherweise bitten, Ihre Identit\u00e4t nachzuweisen, bevor wir weitere Schritte bez\u00fcglich Ihrer Anfrage unternehmen. <\/p>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Datenschutzrichtlinie Diese Datenschutzrichtlinie beschreibt, welche personenbezogenen Daten bei der Nutzung der Website erhoben oder generiert (verarbeitet) werden. Diese Datenschutzrichtlinie beschreibt, welche Arten von personenbezogenen Daten bei der Nutzung unserer Website erhoben werden und wie Ihre personenbezogenen Daten verwendet, weitergegeben und gesch\u00fctzt werden. Au\u00dferdem erl\u00e4utert sie, welche Wahlm\u00f6glichkeiten Sie hinsichtlich Ihrer personenbezogenen Daten haben und wie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"Datenschutzrichtlinie","_seopress_titles_desc":"","_seopress_robots_index":"yes","_seopress_robots_follow":"yes","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_gt_ctv_global_id":"","_gt_ctv_id_group":false,"inline_featured_image":false,"gt_fse_maillage_image":"","gt_fse_maillage_titre":"Datenschutz","gt_fse_maillage_alt":"Datenschutzrichtlinie","gt_fse_maillage_resume":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-13691","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/wp-json\/wp\/v2\/pages\/13691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/wp-json\/wp\/v2\/comments?post=13691"}],"version-history":[{"count":8,"href":"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/wp-json\/wp\/v2\/pages\/13691\/revisions"}],"predecessor-version":[{"id":13740,"href":"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/wp-json\/wp\/v2\/pages\/13691\/revisions\/13740"}],"wp:attachment":[{"href":"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/wp-json\/wp\/v2\/media?parent=13691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/wp-json\/wp\/v2\/categories?post=13691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/haut-de-rosans.geek-tonic.dev\/de\/wp-json\/wp\/v2\/tags?post=13691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}